{"id":6466,"date":"2010-12-15T20:00:53","date_gmt":"2010-12-15T19:00:53","guid":{"rendered":"https:\/\/blogs.plombiers-reunis.com\/?p=6466"},"modified":"2010-12-15T20:00:53","modified_gmt":"2010-12-15T19:00:53","slug":"tout-savoir-sur-les-reseaux-en-acier-galvanise","status":"publish","type":"post","link":"https:\/\/plombiers-reunis.com\/v3\/reseaux\/tout-savoir-sur-les-reseaux-en-acier-galvanise.html","title":{"rendered":"Tout savoir sur les r\u00e9seaux en acier galvanis\u00e9"},"content":{"rendered":"<p>Des canalisations en acier courant ne peuvent \u00eatre utilis\u00e9es dans des installations sanitaires qu\u2019\u00e0 condition qu\u2019elles soient dot\u00e9es d\u2019une couche de zinc.Ce sont des tubes ronds, fabriqu\u00e9s \u00e0 partir de bobine d\u2019acier noir lamin\u00e9 \u00e0 chaud (LAC), form\u00e9s \u00e0 froid, soud\u00e9s par induction \u00e0 haute fr\u00e9quence, puis galvanis\u00e9s \u00e0 chaud par immersion. Ce type de tube, galvanis\u00e9 int\u00e9rieurement et ext\u00e9rieurement, offre une excellente tenue \u00e0 la corrosion.<!--more--><\/p>\n<div class=\"avertissement\">Ce type de tuyaux est tout bonnement interdit dans les installations de chauffage<br \/>\nSur les autres installations, lorsque m\u00e9lang\u00e9 a d&rsquo;autres m\u00e9taux, il provoque l&rsquo;effet de galvanisation (<em>aussi appel\u00e9e l&rsquo;effet p\u00eele ou \u00e9lectrolyse<\/em>).<\/div>\n<h2>Identification\u00a0 des tuyaux<\/h2>\n<p>Les tuyaux galvanis\u00e9s de qualit\u00e9 alimentaire sont marqu\u00e9s par jet d\u2019encre. Dans ce marquage ont trouve essentiellement les donn\u00e9s suivantes:<\/p>\n<ul>\n<li>Fabricant<\/li>\n<li>Diam\u00e8tre<\/li>\n<li>\u00c9paisseur de la paroi<\/li>\n<li>Longueur<\/li>\n<li>Montage<\/li>\n<li>Date &amp; Heure<\/li>\n<li>Origine m\u00e9tal &amp; \u00c9quipe<\/li>\n<\/ul>\n<p>En vue de la formation de la couche complexe de patine protectrice, compos\u00e9e d\u2019oxydes et d\u2019hydroxydes de zinc (pentahydroxycarbonate de zinc), sur la paroi interne du tube, la composition de l\u2019eau distribu\u00e9e rev\u00eat une importance capitale.<\/p>\n<h2 class=\"hrcolor\">Corrosion de la paroi interne du tuyau<\/h2>\n<p><a href=\"https:\/\/plombiers-reunis.com\/v3\/reseaux\/tout-savoir-sur-les-reseaux-en-acier-galvanise.html\/attachment\/eau-rouille\" rel=\"attachment wp-att-6467\"><img class=\"alignright wp-image-6467 size-medium lws-optimize-lazyload\"  alt=\"Eau rouill\u00e9\" width=\"300\" height=\"261\" \/ data-src=\"https:\/\/plombiers-reunis.com\/v3\/medias\/2010\/12\/eau-rouill%C3%A9-300x261.jpg\"><\/a>Lorsque l\u2019eau distribu\u00e9e arrive dans l\u2019installation int\u00e9rieure du b\u00e2timent, elle subit un certain nombre de modifications physiques (pression, temp\u00e9rature, \u2026) qui peuvent avoir un impact sur la composition chimique de l\u2019eau. D\u2019autres traitements (adoucissements, p. ex.) peuvent \u00e9galement modifier la qualit\u00e9 de l\u2019eau.<\/p>\n<p>La p\u00e9n\u00e9tration de particules solides (sable, argile, limon, \u2026) entra\u00een\u00e9es par l\u2019eau distribu\u00e9e peut exercer une grande influence sur l\u2019apparition d\u2019un type de corrosion d\u00e9termin\u00e9. La quantit\u00e9 de particules solides qui p\u00e9n\u00e8trent dans l\u2019installation peut par exemple augmenter en raison de travaux sur la conduite principale. L\u2019assemblage et le stockage de tuyaux dans un environnement poussi\u00e9reux ou encore la p\u00e9n\u00e9tration de limaille de fer lors de leur usinage peuvent aussi faire en sorte que des particules solides se retrouvent dans l\u2019installation.<\/p>\n<p>Ces particules solides peuvent se d\u00e9poser sur la paroi interne du tuyau (et plus particuli\u00e8rement dans les tron\u00e7ons horizontaux), entra\u00eenant une corrosion par a\u00e9ration diff\u00e9rentielle, aussi appel\u00e9e corrosion sous d\u00e9p\u00f4ts.<\/p>\n<p>Le cas \u00e9ch\u00e9ant, la partie inf\u00e9rieure du tuyau pr\u00e9sente des nodules de corrosion localis\u00e9s, qui peuvent donner lieu au percement de la paroi du tuyau. Il ne s\u2019agit en d\u2019autres termes pas d\u2019une diminution g\u00e9n\u00e9rale de l\u2019\u00e9paisseur de la paroi, mais bien d\u2019une perforation rapide et localis\u00e9e (corrosion par piq\u00fbres).<\/p>\n<h2>Les diam\u00e8tres et les accessoires<\/h2>\n<p>Pour r\u00e9pondre aux questions qui surviennent souvent sur les forums de plomberie concernant les diam\u00e8tre des tubes acier, malgr\u00e9 que ce type de tubes est de moins en moins utilis\u00e9 de nous jours.<\/p>\n<p>Comme les cintrage de ce type de tubes est assez laborieux et exige l\u2019utilisation d\u2019un cintreuse hydraulique, m\u00eame avec des rayons de cintrage \u00e9normes, l\u2019utilisation des raccords est tr\u00e8s courante en vue de simplifier la mise en \u0153uvre.<\/p>\n<p>Voici donc les diam\u00e8tres et les rayons des coudes ainsi que les \u00e9paisseurs de la paroi du tuyau.<\/p>\n<h2><a href=\"https:\/\/plombiers-reunis.com\/v3\/reseaux\/tout-savoir-sur-les-reseaux-en-acier-galvanise.html\/attachment\/diametres-tuyaux\" rel=\"attachment wp-att-6468\"><img class=\"size-full wp-image-6468 alignnone lws-optimize-lazyload\"  alt=\"Diam\u00e8tres des tuyaux galvanis\u00e9s\" width=\"974\" height=\"493\" \/ data-src=\"https:\/\/plombiers-reunis.com\/v3\/medias\/2010\/12\/diametres-tuyaux.jpg\"><\/a><br \/>\nRayons des coudes<\/h2>\n<table style=\"width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">\u00d8 externe X \u00e9paisseur de paroi en Mm<\/td>\n<td style=\"text-align: center; width: 16.579%;\">Pouces<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">Rayon des<br \/>\ncoudes 90\u00b0 en Cm<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">Longueur du coude \u00e0 45\u00b0 en Cm<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">Longueur du coude \u00e0 30\u00b0\u00a0 en Cm<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">26.9 x 2.3<\/td>\n<td style=\"text-align: center; width: 16.579%;\">3\/4<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">28,5<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">11,8<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">7,6<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">33.7 x 2.9<\/td>\n<td style=\"text-align: center; width: 16.579%;\">1<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">38<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">15,7<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">10,2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">42.4 x 2.9<\/td>\n<td style=\"text-align: center; width: 16.579%;\">1 \u00bc<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">47,5<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">19,7<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">12,7<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">48.3 x 2.9<\/td>\n<td style=\"text-align: center; width: 16.579%;\">1 \u00bd<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">57<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">23,6<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">15,3<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">60.3 x 3.2<\/td>\n<td style=\"text-align: center; width: 16.579%;\">2<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">76<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">31,5<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">20,4<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">76.1 x 3.2<\/td>\n<td style=\"text-align: center; width: 16.579%;\">2 \u00bd<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">95<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">39,4<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">25,5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">88.9 x 3.2<\/td>\n<td style=\"text-align: center; width: 16.579%;\">3<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">114,5<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">47,4<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">30,7<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">101.6 x 3.6<\/td>\n<td style=\"text-align: center; width: 16.579%;\">3 \u00bd<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">133,5<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">55,3<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">35,8<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">114.3 x 3.6<\/td>\n<td style=\"text-align: center; width: 16.579%;\">4<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">152,5<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">63,2<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">40,9<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">139.7 x 4.0<\/td>\n<td style=\"text-align: center; width: 16.579%;\">5<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">190,5<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">78,9<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">51<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">168.3 x 4.5<\/td>\n<td style=\"text-align: center; width: 16.579%;\">6<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">228,5<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">94,7<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">61,2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">219.1 x 6.3<\/td>\n<td style=\"text-align: center; width: 16.579%;\">8<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">305<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">126,4<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">81,7<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">273 x 6.3<\/td>\n<td style=\"text-align: center; width: 16.579%;\">10<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">381<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">157,8<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">102,1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">323.9 x 7.1<\/td>\n<td style=\"text-align: center; width: 16.579%;\">12<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">457<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">189,3<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">122,5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">355.6 x 8.0<\/td>\n<td style=\"text-align: center; width: 16.579%;\">14<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">533,5<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">221<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">143<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 24.7369%;\">406.4 x 8.8<\/td>\n<td style=\"text-align: center; width: 16.579%;\">16<\/td>\n<td style=\"text-align: center; width: 18.2894%;\">609,5<\/td>\n<td style=\"text-align: center; width: 19.0789%;\">252,5<\/td>\n<td style=\"text-align: center; width: 19.7368%;\">163,3<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Toutefois ce type de tuyaux deviens de moins en moins utilis\u00e9 dans les installation de type sanitaire, compte tenu de la corrosion trop importante de l\u2019int\u00e9rieur du tuyaux au fil du temps en plus avec les nouvelles normes il deviens d\u00e9conseill\u00e9 de souder questions d&rsquo;\u00e9cologie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des canalisations en acier courant ne peuvent \u00eatre utilis\u00e9es dans des installations sanitaires qu\u2019\u00e0 condition qu\u2019elles soient dot\u00e9es d\u2019une couche de zinc.Ce sont des tubes ronds, fabriqu\u00e9s \u00e0 partir de bobine d\u2019acier noir lamin\u00e9 \u00e0 chaud (LAC), form\u00e9s \u00e0 froid, soud\u00e9s par induction \u00e0 haute fr\u00e9quence, puis galvanis\u00e9s \u00e0 chaud par immersion. Ce type de &#8230; <a title=\"Tout savoir sur les r\u00e9seaux en acier galvanis\u00e9\" class=\"read-more\" href=\"https:\/\/plombiers-reunis.com\/v3\/reseaux\/tout-savoir-sur-les-reseaux-en-acier-galvanise.html\" aria-label=\"En savoir plus sur Tout savoir sur les r\u00e9seaux en acier galvanis\u00e9\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":6467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[5],"tags":[48,49,586,1376],"class_list":["post-6466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reseaux","tag-acier","tag-acier-galva","tag-galva","tag-tuyaux-galva"],"_links":{"self":[{"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/posts\/6466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/comments?post=6466"}],"version-history":[{"count":0,"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/posts\/6466\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/media\/6467"}],"wp:attachment":[{"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/media?parent=6466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/categories?post=6466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/tags?post=6466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}