{"id":420,"date":"2021-07-09T08:00:00","date_gmt":"2021-07-09T07:00:00","guid":{"rendered":"http:\/\/www.petitplombier.com\/?p=420"},"modified":"2021-07-09T08:00:00","modified_gmt":"2021-07-09T07:00:00","slug":"les-outils-de-grande-marque","status":"publish","type":"post","link":"https:\/\/plombiers-reunis.com\/v3\/outillage-et-materiaux\/les-outils-de-grande-marque.html","title":{"rendered":"Les outils de grande marque"},"content":{"rendered":"\n<p>D&rsquo;une mani\u00e8re g\u00e9n\u00e9rale, les plombiers utilisent toujours des outils de grande marque, a tel point que certains fabricants se sont sp\u00e9cialis\u00e9s dans la fabrication d&rsquo;outillage pour le plombier.<\/p>\n\n\n\n<p>Il faut savoir que les outils de qualit\u00e9, sont incontournables dans la r\u00e9alisation de travaux de qualit\u00e9 professionnelle.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Pour ma part j&rsquo;ai un faible pour les outils a la marque rouge, et derni\u00e8rement je me suis laiss\u00e9 tenter  une nouveaut\u00e9, le set de tournevis magn\u00e9tiques que l&rsquo;on trouve dans certains magasins au prix public conseill\u00e9 de 75\u20ac (<em>tout de m\u00eame<\/em>).<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/plombiers-reunis.com\/v3\/?attachment_id=7529\"><img  alt=\"set de tournevis Virax\" class=\"wp-image-7529 lws-optimize-lazyload\"\/ width=\"900\" height=\"506\" data-src=\"https:\/\/plombiers-reunis.com\/v3\/wp-content\/uploads\/2023\/05\/set-de-tournevis-magnetiques-virax.jpg\" srcset=\"https:\/\/plombiers-reunis.com\/v3\/wp-content\/uploads\/2023\/05\/set-de-tournevis-magnetiques-virax.jpg 900w, https:\/\/plombiers-reunis.com\/v3\/wp-content\/uploads\/2023\/05\/set-de-tournevis-magnetiques-virax-300x169.jpg 300w, https:\/\/plombiers-reunis.com\/v3\/wp-content\/uploads\/2023\/05\/set-de-tournevis-magnetiques-virax-768x432.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><figcaption class=\"wp-element-caption\">Cr\u00e9dit image: Virax<\/figcaption><\/figure>\n<\/div>\n\n\n<p>La joie fut de courte dur\u00e9e car lors des premi\u00e8res utilisations le tournevis cruciforme de taille moyenne a rendu l\u2019\u00e2me.<\/p>\n\n\n\n<p>La tige m\u00e9tallique est cass\u00e9 a l\u2019int\u00e9rieur de la poign\u00e9e.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/plombiers-reunis.com\/v3\/?attachment_id=7530\"><img  alt=\"Tourne vis cass\u00e9\" class=\"wp-image-7530 lws-optimize-lazyload\"\/ width=\"1024\" height=\"473\" data-src=\"https:\/\/plombiers-reunis.com\/v3\/medias\/2023\/05\/Tourne-vis-garantis-a-vie-1024x473.jpg\" srcset=\"https:\/\/plombiers-reunis.com\/v3\/wp-content\/uploads\/2023\/05\/Tourne-vis-garantis-a-vie-1024x473.jpg 1024w, https:\/\/plombiers-reunis.com\/v3\/wp-content\/uploads\/2023\/05\/Tourne-vis-garantis-a-vie-300x139.jpg 300w, https:\/\/plombiers-reunis.com\/v3\/wp-content\/uploads\/2023\/05\/Tourne-vis-garantis-a-vie-768x355.jpg 768w, https:\/\/plombiers-reunis.com\/v3\/wp-content\/uploads\/2023\/05\/Tourne-vis-garantis-a-vie-1536x709.jpg 1536w, https:\/\/plombiers-reunis.com\/v3\/wp-content\/uploads\/2023\/05\/Tourne-vis-garantis-a-vie.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>Quelques jours plus tard, c&rsquo;est au tour du tournevis plat, de casser a son tour, au m\u00eame endroit. Bizarre non ?<\/p>\n\n\n\n<p>Apr\u00e8s inspection je dirais qu&rsquo;il s&rsquo;agit d&rsquo;un d\u00e9faut de fabrication, le point de soudure qui la forme six-pans (<em>permanentant l&rsquo;usage d&rsquo;une cl\u00e9 de dix pour tourner<\/em>) sur la tige du tournevis a fragilis\u00e9 ce dernier a tel point qu&rsquo;il casse au moindre effort.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/plombiers-reunis.com\/v3\/?attachment_id=7531\"><img  alt=\"second tournevis cass\u00e9\" class=\"wp-image-7531 lws-optimize-lazyload\"\/ width=\"1024\" height=\"545\" data-src=\"https:\/\/plombiers-reunis.com\/v3\/medias\/2023\/05\/tourne-vis-casse-1024x545.jpg\" srcset=\"https:\/\/plombiers-reunis.com\/v3\/wp-content\/uploads\/2023\/05\/tourne-vis-casse-1024x545.jpg 1024w, https:\/\/plombiers-reunis.com\/v3\/wp-content\/uploads\/2023\/05\/tourne-vis-casse-300x160.jpg 300w, https:\/\/plombiers-reunis.com\/v3\/wp-content\/uploads\/2023\/05\/tourne-vis-casse-768x409.jpg 768w, https:\/\/plombiers-reunis.com\/v3\/wp-content\/uploads\/2023\/05\/tourne-vis-casse.jpg 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>Je ne sais pas si ce d\u00e9faut concerne toute la s\u00e9rie ou seulement celle que j&rsquo;ai achet\u00e9, mais dans tous cas je dirais que le fabricant devrait rappeler tous les sets pas encore vendu pour v\u00e9rification.<\/p>\n\n\n\n<p>Ceci est encore une faille qui accentue ma volont\u00e9 d&rsquo;aller voir la concurrence pour ce type d&rsquo;outillage.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D&rsquo;une mani\u00e8re g\u00e9n\u00e9rale, les plombiers utilisent toujours des outils de grande marque, a tel point que certains fabricants se sont sp\u00e9cialis\u00e9s dans la fabrication d&rsquo;outillage pour le plombier. Il faut savoir que les outils de qualit\u00e9, sont incontournables dans la r\u00e9alisation de travaux de qualit\u00e9 professionnelle.<\/p>\n","protected":false},"author":1,"featured_media":7529,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[20],"tags":[837,838,840],"class_list":["post-420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outillage-et-materiaux","tag-outillage-de-marque","tag-outils-du-plombier","tag-outils-virax"],"_links":{"self":[{"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/posts\/420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/comments?post=420"}],"version-history":[{"count":0,"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/posts\/420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/media\/7529"}],"wp:attachment":[{"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/media?parent=420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/categories?post=420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plombiers-reunis.com\/v3\/wp-json\/wp\/v2\/tags?post=420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}